{"id":45108,"date":"2020-06-04T06:00:52","date_gmt":"2020-06-04T04:00:52","guid":{"rendered":"https:\/\/blog.apartmentbarcelona.com\/sagrada-familia-barcelona-3\/"},"modified":"2024-12-05T22:25:16","modified_gmt":"2024-12-05T21:25:16","slug":"sagrada-familia-barcelona-3","status":"publish","type":"post","link":"https:\/\/blog.apartmentbarcelona.com\/fr\/sagrada-familia-barcelona-3\/","title":{"rendered":"D\u00e9couvrez la Sagrada Familia de Barcelone"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-34563 alignright\" src=\"https:\/\/blog.apartmentbarcelona.com\/wp-content\/uploads\/2015\/01\/Sagrada-Familia.jpg\" alt=\"sagrada familia\" width=\"187\" height=\"275\" \/>Construite par l&#8217;architecte de renomm\u00e9e mondiale, <strong>Antoni Gaud\u00ed,<\/strong> la <strong>Sagrada Familia<\/strong> est le monument le plus connu de Barcelone. Avec son apparence haute, elle peut \u00eatre admir\u00e9e de tous les points de vue dans et autour de la ville. Elle est visit\u00e9e par des gens du monde entier et poss\u00e8de sa propre station de m\u00e9tro qui vous surprendra lorsque vous monterez les escaliers et qu&#8217;elle vous surplombera. Nous avons pens\u00e9 vous donner l&#8217;occasion de <strong>d\u00e9couvrir la Sagrada Familia depuis chez vous,<\/strong> avec ses caract\u00e9ristiques caract\u00e9ristiques caract\u00e9ristiques, son int\u00e9rieur et ses toits \u00e9tonnants qui captent brillamment l&#8217;imagination. Ainsi, vous saurez \u00e0 quoi vous attendre lors de votre prochaine visite \u00e0 Barcelone.<\/p>\n<p>&nbsp;<\/p>\n<h2>Fa\u00e7ades<\/h2>\n<p>La premi\u00e8re chose que vous pourrez appr\u00e9cier en arrivant \u00e0 la Sagrada Familia, ce sont ses belles fa\u00e7ades qui r\u00e9v\u00e8lent des histoires \u00e0 travers leur <strong>conception artistique.<\/strong> Deux sont propos\u00e9es, la premi\u00e8re est connue sous le nom de <strong>Fa\u00e7ade de la Nativit\u00e9, <\/strong>qui fait un clin d&#8217;\u0153il \u00e0 l&#8217;histoire du Christ et au cheminement de la vie. Des sculptures d&#8217;animaux aux repr\u00e9sentations de la Bible, cette fa\u00e7ade invoque une compr\u00e9hension profonde qui permet de l&#8217;interpr\u00e9ter de nombreuses fa\u00e7ons. Construite entre les ann\u00e9es 1890 et 1930, <strong>Gaud\u00ed<\/strong> a voulu que les figures de cette fa\u00e7ade soient peintes, afin de lui donner <strong>une nouvelle vie<\/strong>. M\u00eame si cela n&#8217;est pas devenu r\u00e9alit\u00e9, c&#8217;est vraiment \u00e9poustouflant.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-34562 aligncenter\" src=\"https:\/\/blog.apartmentbarcelona.com\/wp-content\/uploads\/2020\/06\/nativity-facade.jpg\" alt=\"nativity facade\" width=\"412\" height=\"309\" \/><\/p>\n<p>La seconde fa\u00e7ade est beaucoup plus r\u00e9cente, connue sous le nom de<strong> fa\u00e7ade de la Passion,<\/strong> elle a \u00e9t\u00e9 construite en second lieu \u00e0 la demande de Gaud\u00ed, car il pensait que si les travaux commen\u00e7aient avec cet ext\u00e9rieur brutal, alors les Barcelonais perdraient tout int\u00e9r\u00eat pour le b\u00e2timent avant son ach\u00e8vement. Il pensait en effet que si les travaux commen\u00e7aient par cette fa\u00e7ade brutale, les Barcelonais se d\u00e9sint\u00e9resseraient du b\u00e2timent avant son ach\u00e8vement. Il a donc d\u00e9cid\u00e9 de <strong>concevoir librement la fa\u00e7ade de la Passion<\/strong>, ce qui a suscit\u00e9 un int\u00e9r\u00eat positif d\u00e8s le d\u00e9but. Celle-ci, un autre \u00e9l\u00e9ment de l&#8217;imagerie religieuse, montre la<strong> pierre nue<\/strong> de mani\u00e8re \u00e0 repr\u00e9senter des os, qui travaille \u00e0 compl\u00e9ter une image de la crucifixion du Christ, comme une mani\u00e8re de montrer les p\u00e9ch\u00e9s de l&#8217;homme. Ce dessin brutal capte l&#8217;attention et laisse les plus perturb\u00e9s &#8211; exactement ce que Gaud\u00ed aurait voulu.<strong> Divis\u00e9 en trois sections,<\/strong> la base montre la C\u00e8ne et le <strong>baiser de Judas<\/strong>, la seconde fait allusion \u00e0 la crucifixion et \u00e0 la pr\u00e9sence des trois Maries : la section sup\u00e9rieure symbolisant l&#8217;enterrement et la r\u00e9surrection. Une architecture haute et imposante qui rappelle<strong> La Pedrera de Barcelone.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-34561 aligncenter\" src=\"https:\/\/blog.apartmentbarcelona.com\/wp-content\/uploads\/2020\/06\/passion-facade.jpg\" alt=\"passion facade\" width=\"371\" height=\"278\" \/><\/p>\n<p>La troisi\u00e8me et derni\u00e8re fa\u00e7ade est connue sous le nom de &#8220;<strong>Glory Facade<\/strong>&#8221; et est la plus grande des trois. Avec ses multiples entr\u00e9es et ses <strong>nombreuses vitres,<\/strong> elle repr\u00e9sente la mort, le jour du jugement dernier et la gloire \u00e9ternelle. La construction a commenc\u00e9 en 2002 et la partie la plus remarquable de cette fa\u00e7ade est probablement <strong>la Porte de l&#8217;Eucharistie<\/strong>, achev\u00e9e en 2008, sur laquelle est inscrit le Notre P\u00e8re.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-34560 aligncenter\" src=\"https:\/\/blog.apartmentbarcelona.com\/wp-content\/uploads\/2020\/06\/glory-facade.jpg\" alt=\"glory facade\" width=\"332\" height=\"249\" \/><\/p>\n<h2>Int\u00e9rieur<\/h2>\n<p>Aussi \u00e9tonnant que soit l&#8217;ext\u00e9rieur de la Sagrada Familia,<strong> l&#8217;art se poursuit \u00e0 l&#8217;int\u00e9rieur<\/strong> de cette magnifique basilique. Comme le dit le clich\u00e9, les mots ne rendent pas justice \u00e0 cet endroit. Avec son architecture \u00e9tonnante, cet endroit pr\u00e9sente des <strong>plafonds hauts et courb\u00e9s<\/strong> et des piliers imposants, dont la conception pure est in\u00e9dite dans le monde. L&#8217;agencement astucieux des nombreux vitraux, pour la plupart de conception moderne, relie cette fondation embl\u00e9matique. La <strong>lumi\u00e8re danse<\/strong> tout simplement autour de la basilique et fascine tous ceux qui la visitent.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-34558 aligncenter\" src=\"https:\/\/blog.apartmentbarcelona.com\/wp-content\/uploads\/2020\/06\/stained-glass-sagrada-familia.jpg\" alt=\"stained glass sagrada familia\" width=\"424\" height=\"309\" \/><\/p>\n<p>La pi\u00e8ce la plus unique de tout l&#8217;int\u00e9rieur est certainement l&#8217;utilisation de fen\u00eatres dans le toit, qui donnent un certain nombre de<strong> spots et de faisceaux<\/strong> qui donnent une lueur c\u00e9leste. En plus de cela, il y a bien s\u00fbr des bancs et un autel, avec une croix suspendue au-dessus, ainsi qu&#8217;une crypte et <strong>la tombe de Gaudi &#8211;<\/strong> mais nous y reviendrons plus tard.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-34559 aligncenter\" src=\"https:\/\/blog.apartmentbarcelona.com\/wp-content\/uploads\/2020\/06\/interior-sagrada-familia.jpg\" alt=\"interior sagrada familia\" width=\"490\" height=\"280\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2>Sur le toit<\/h2>\n<p>Une fois la Sagrada Familia termin\u00e9e, le toit sera la partie la plus embl\u00e9matique du b\u00e2timent. Nous disons cela parce que c&#8217;est l\u00e0 que toutes les tours se rejoindront et aussi que Gaud\u00ed a laiss\u00e9 quelques surprises. Ses sculptures embl\u00e9matiques qui couvrent le parc<strong> Guel<\/strong>l et le toit de la Casa Batll\u00f3, des finitions<strong> color\u00e9es et carrel\u00e9es qui sont sa signature,<\/strong> se trouveront au sommet de la Sagrada Familia. De plus, comme vous pouvez le voir sur la visite virtuelle de la Sagrada Familia, le toit offre une vue panoramique incroyable de Barcelone, vous donnant une vue de la ville depuis le ciel. Nous ne pouvons pas attendre que ces travaux soient termin\u00e9s !<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-34557 aligncenter\" src=\"https:\/\/blog.apartmentbarcelona.com\/wp-content\/uploads\/2020\/06\/view-sagrada-familia-scaled.jpg\" alt=\"view sagrada familia\" width=\"3216\" height=\"2136\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2>La tombe de Gaud\u00ed<\/h2>\n<p>Enfin, il est important de rappeler que la Sagrada Familia de Barcelone est la derni\u00e8re demeure d&#8217;<strong>Antoni Gaud\u00ed (1852-1926)<\/strong>. Situ\u00e9e dans les cryptes de cette basilique, cette partie calme et paisible de la Sagrada Familia nous permet \u00e0 tous de r\u00e9fl\u00e9chir \u00e0 la vie brillante que Gaud\u00ed a eue et \u00e0 l&#8217;incroyable travail qu&#8217;il a accompli, qui a transform\u00e9 Barcelone comme personne ne l&#8217;a fait avant, ni depuis. <strong>Il y a \u00e9galement une petite chapelle ici,<\/strong> qui permet de pratiquer le culte en groupe dans cette partie isol\u00e9e de la Sagrada Familia. Une autre personne est \u00e9galement enterr\u00e9e ici, il s&#8217;agit de <strong>Josep Maria Bocabella,<\/strong> un philanthrope local qui a eu l&#8217;id\u00e9e de cr\u00e9er la Sagrada Familia \u00e0 la fin du XIXe si\u00e8cle. Sans lui, Gaud\u00ed n&#8217;aurait eu aucune raison r\u00e9elle de construire cette \u0153uvre d&#8217;art \u00e9tonnante, et Barcelone serait priv\u00e9e de l&#8217;un de ses monuments les plus c\u00e9l\u00e8bres. Nous sommes tr\u00e8s reconnaissants envers <strong>Bocabella<\/strong> et, bien s\u00fbr, envers Gaud\u00ed.<img loading=\"lazy\" decoding=\"async\" class=\" wp-image-34556 aligncenter\" src=\"https:\/\/blog.apartmentbarcelona.com\/wp-content\/uploads\/2020\/06\/Gaudi-tomb.jpg\" alt=\"Gaudi tomb\" width=\"525\" height=\"394\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La principale attraction de Barcelone, la Sagrada Familia, construite par Antoni Gaud\u00ed, accueille chaque jour des milliers de visiteurs. De l&#8217;ext\u00e9rieur \u00e0 l&#8217;int\u00e9rieur, cette basilique abrite des \u0153uvres d&#8217;art \u00e9tonnantes, une conception architecturale fantastique et de merveilleuses sculptures. Pour en savoir plus, consultez cet article et faites la queue pour d\u00e9couvrir la Sagrada Familia de Barcelone<\/p>\n","protected":false},"author":1,"featured_media":45061,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[92,205,209,192,195,204],"tags":[599,597],"class_list":["post-45108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-guia-turistica","category-informacion-util","category-page-daccueil","category-que-hacer","category-sitios","category-vida-local","tag-tourisme-barcelone","tag-visiter-barcelone-2"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blog.apartmentbarcelona.com\/fr\/wp-json\/wp\/v2\/posts\/45108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.apartmentbarcelona.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.apartmentbarcelona.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.apartmentbarcelona.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.apartmentbarcelona.com\/fr\/wp-json\/wp\/v2\/comments?post=45108"}],"version-history":[{"count":1,"href":"https:\/\/blog.apartmentbarcelona.com\/fr\/wp-json\/wp\/v2\/posts\/45108\/revisions"}],"predecessor-version":[{"id":45109,"href":"https:\/\/blog.apartmentbarcelona.com\/fr\/wp-json\/wp\/v2\/posts\/45108\/revisions\/45109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.apartmentbarcelona.com\/fr\/wp-json\/wp\/v2\/media\/45061"}],"wp:attachment":[{"href":"https:\/\/blog.apartmentbarcelona.com\/fr\/wp-json\/wp\/v2\/media?parent=45108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.apartmentbarcelona.com\/fr\/wp-json\/wp\/v2\/categories?post=45108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.apartmentbarcelona.com\/fr\/wp-json\/wp\/v2\/tags?post=45108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}